{"id":620029,"date":"2019-11-29T17:01:01","date_gmt":"2019-11-29T20:01:01","guid":{"rendered":"http:\/\/www.oroverde.com.ar\/web\/?p=620029"},"modified":"2019-12-06T18:01:52","modified_gmt":"2019-12-06T21:01:52","slug":"oro-verde-implementara-un-sistema-de-monitoreo-ambiental-continuo-de-contaminantes-agricolas","status":"publish","type":"post","link":"https:\/\/www.oroverde.com.ar\/web\/oro-verde-implementara-un-sistema-de-monitoreo-ambiental-continuo-de-contaminantes-agricolas\/","title":{"rendered":"Oro Verde implementar\u00e1 un sistema de monitoreo ambiental continuo de contaminantes agr\u00edcolas"},"content":{"rendered":"\n<p>Las Facultades de\nIngenier\u00eda y Ciencias Agropecuarias de UNER, el Municipio y el INTA\nfirmaron un convenio para poner en marcha el \u201cPlan de Monitoreo\nAmbiental del Municipio de Oro Verde\u201d. Iniciativa que tiene como\neje fundamental responder a la demanda de vecinos y el Gobierno\nlocal, y detectar\u00e1 contaminantes agr\u00edcolas en suelo, agua\nsubterr\u00e1nea y aire en sitios estrat\u00e9gicos.<\/p>\n\n\n\n<p>El intendente de\nOro Verde, Jos\u00e9 Luis Dum\u00e9, recibi\u00f3 esta ma\u00f1ana al decano de la\nFacultad de Ingenier\u00eda, Diego Campana, junto al director Estaci\u00f3n\nExperimental Agropecuaria INTA Paran\u00e1, Rub\u00e9n Isaurralde, para\nrubricar un acta para la implementaci\u00f3n de este proyecto que se\nenmarca en las Estrategias de Articulaci\u00f3n Territorial que propicia\nla universidad.<\/p>\n\n\n\n<p>Los tres\nobjetivos planteados son, atender la inquietud de la poblaci\u00f3n local\nrespecto al impacto de la actividad agropecuaria en Oro Verde; y,\nconformar un plan de monitoreo de suelo, agua subterr\u00e1nea y aire en\nsitios geoposicionados estrat\u00e9gicamente con metodolog\u00eda anal\u00edtica\ny procedimientos para la detecci\u00f3n de contaminantes agr\u00edcolas. Por\n\u00faltimo, fortalecer capacidades y, generar y transferir conocimiento\npara minimizar los impactos ambientales asociados a la producci\u00f3n\nagr\u00edcola o para implementar medidas de remediaci\u00f3n.<\/p>\n\n\n\n<p>Al respecto,\nCampana afirm\u00f3 \u201ces un acontecimiento muy importante, uno de los\nproyectos firmados dentro de una nueva estrategia que ha pensado la\nUNER, un sistema de proyectos en el cual la din\u00e1mica es diferente:\nse realizan mesas donde la Universidad se sienta a escuchar las\ndemandas del medio. Es decir, abre sus puertas a organizaciones\nprivadas, p\u00fablicas en este caso, y organizaciones sociales, que\nvienen a plantear una problem\u00e1tica. Toma la demanda, se la escucha y\neval\u00faa c\u00f3mo se pueden articular estrategias para darle soluci\u00f3n,\nmirando no s\u00f3lo los recursos propios y los del demandante, en este\ncaso el Municipio. Tambi\u00e9n las capacidades desarrolladas de otros\nactores, como por ejemplo el INTA, por lo que la Universidad se\ntransforma en esa amalgama, ese catalizador de esta propuesta de\nsoluci\u00f3n a una problem\u00e1tica en particular\u201d.<\/p>\n\n\n\n<p>Por su parte, el\npresidente municipal se\u00f1al\u00f3 \u201cpara nosotros este Plan de Monitoreo\nAmbiental es un paso m\u00e1s en la pol\u00edtica ambiental que el Municipio\nviene desarrollando, y para esto se ha fijado metas. Una de ellas es\neste plan, que pone en valor las potencialidades de la localidad,\ndonde conviven algunas de las instituciones de generaci\u00f3n de\nconocimiento m\u00e1s prestigiosas de la provincia. Adem\u00e1s, responde a\nla demanda que hacen nuestros vecinos, y a su vez, nos permitir\u00e1\ntener datos concretos a fin de aplicar medidas o corregir pr\u00e1cticas.\nServir\u00e1 seguramente para trasladar como experiencia a otras\nlocalidades que quieran tener datos certeros del impacto de la\nactividad agropecuaria en sus comunidades\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Facultades de Ingenier\u00eda y Ciencias Agropecuarias de UNER, el Municipio y el INTA firmaron un convenio para poner en marcha el \u201cPlan de Monitoreo Ambiental del Municipio de Oro&#8230;<\/p>\n","protected":false},"author":1,"featured_media":620035,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[32,38,5],"tags":[],"class_list":["post-620029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente-saludable","category-convenios","category-noticias-municipales","wpcat-32-id","wpcat-38-id","wpcat-5-id"],"_links":{"self":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/620029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/comments?post=620029"}],"version-history":[{"count":1,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/620029\/revisions"}],"predecessor-version":[{"id":620045,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/620029\/revisions\/620045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media\/620035"}],"wp:attachment":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media?parent=620029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/categories?post=620029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/tags?post=620029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}