{"id":624192,"date":"2021-09-20T19:45:15","date_gmt":"2021-09-20T22:45:15","guid":{"rendered":"https:\/\/www.oroverde.com.ar\/web\/?p=624192"},"modified":"2021-09-20T19:45:16","modified_gmt":"2021-09-20T22:45:16","slug":"se-reunieron-en-oro-verde-los-intendentes-vecinalistas-de-la-provincia","status":"publish","type":"post","link":"https:\/\/www.oroverde.com.ar\/web\/se-reunieron-en-oro-verde-los-intendentes-vecinalistas-de-la-provincia\/","title":{"rendered":"Se reunieron en Oro Verde los intendentes vecinalistas de la provincia."},"content":{"rendered":"\n<p>El intendente Oscar Toledo, y la viceintendenta, Marianela Komar, recibieron a los jefes comunales vecinalistas de la provincia. Se reunieron en el Quincho de Polideportivo municipal, junto a sus equipos de trabajo para intercambiar experiencias, hablar de cada una de las gestiones que se llevan adelante a nivel nacional y provincial.<br>Al respecto, el intendente Oscar Toledo afirm\u00f3 \u00abparticipamos de la reuni\u00f3n todos los intendentes para evaluar las gestiones a distintos niveles para tambi\u00e9n abordar tem\u00e1ticas en conjunto, porque compartimos preocupaciones y necesidades que son comunes. Tambi\u00e9n, como lo hacemos en cada uno de los encuentros, compartimos las experiencias de trabajo en cada una de nuestras localidades\u201d.<br>Estuvieron presentes los presidentes comunales Jos\u00e9 Luis Walser (Col\u00f3n), Vanina Pierini (Villa del Rosario), Cristina Boeri (Lucas Gonz\u00e1lez), Rogelio Sanandrea (Santa Ana), Ra\u00fal Casali (Libertador San Mart\u00edn), Mauricio Davico (Pueblo Belgrano), Jos\u00e9 Palacios (Cerrito), Ariel Panozzo (Los Charr\u00faas) y Mario Socolovsky (Valle Mar\u00eda).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente Oscar Toledo, y la viceintendenta, Marianela Komar, recibieron a los jefes comunales vecinalistas de la provincia. Se reunieron en el Quincho de Polideportivo municipal, junto a sus equipos&#8230;<\/p>\n","protected":false},"author":6,"featured_media":624193,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[6,79,12,1,5],"tags":[],"class_list":["post-624192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-de-eventos","category-gestion","category-instituciones","category-noticias","category-noticias-municipales","wpcat-6-id","wpcat-79-id","wpcat-12-id","wpcat-1-id","wpcat-5-id"],"_links":{"self":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/comments?post=624192"}],"version-history":[{"count":1,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624192\/revisions"}],"predecessor-version":[{"id":624194,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624192\/revisions\/624194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media\/624193"}],"wp:attachment":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media?parent=624192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/categories?post=624192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/tags?post=624192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}