{"id":624211,"date":"2021-09-22T19:55:36","date_gmt":"2021-09-22T22:55:36","guid":{"rendered":"https:\/\/www.oroverde.com.ar\/web\/?p=624211"},"modified":"2021-09-22T19:55:38","modified_gmt":"2021-09-22T22:55:38","slug":"comenzo-la-plantacion-de-arboles-en-escuelas-que-participaron-del-eco-canje","status":"publish","type":"post","link":"https:\/\/www.oroverde.com.ar\/web\/comenzo-la-plantacion-de-arboles-en-escuelas-que-participaron-del-eco-canje\/","title":{"rendered":"Comenz\u00f3 la plantaci\u00f3n de \u00e1rboles en escuelas que participaron del Eco Canje."},"content":{"rendered":"\n<p>En el marco de la convocatoria realizada por el programa GIRSU a las escuelas en la que participaron del Eco Canje de manera colectiva, estudiantes y profesores plantaron un \u00e1rbol en la Escuela Rosario Vera Pe\u00f1aloza. Fue parte del acto, la viceintendenta Marianela Komar y el responsable de Ambiente, Javier Fern\u00e1ndez, que hicieron entrega de un fresno y plantines a la vicedirectora, Lorena Marcos.<\/p>\n\n\n\n<p>Antes de plantar el \u00e1rbol en el patio de la escuela, la viceintendenta y el responsable de Ambiente reflexionaron acerca de la importancia del cuidado del medio ambiente, y la vinculaci\u00f3n con las instituciones educativas de la ciudad para amplificar cada una de estas acciones.<\/p>\n\n\n\n<p>Durante la semana continuar\u00e1 la entrega de \u00e1rboles en otras instituciones educativas de la localidad y la regi\u00f3n que recolectaron sus residuos recuperables para el \u00faltimo Eco Canje.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la convocatoria realizada por el programa GIRSU a las escuelas en la que participaron del Eco Canje de manera colectiva, estudiantes y profesores plantaron un \u00e1rbol&#8230;<\/p>\n","protected":false},"author":6,"featured_media":624212,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[6,12,1,5],"tags":[],"class_list":["post-624211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-de-eventos","category-instituciones","category-noticias","category-noticias-municipales","wpcat-6-id","wpcat-12-id","wpcat-1-id","wpcat-5-id"],"_links":{"self":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/comments?post=624211"}],"version-history":[{"count":1,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624211\/revisions"}],"predecessor-version":[{"id":624213,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624211\/revisions\/624213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media\/624212"}],"wp:attachment":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media?parent=624211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/categories?post=624211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/tags?post=624211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}