{"id":624526,"date":"2021-12-21T19:23:19","date_gmt":"2021-12-21T22:23:19","guid":{"rendered":"https:\/\/www.oroverde.com.ar\/web\/?p=624526"},"modified":"2021-12-21T19:23:21","modified_gmt":"2021-12-21T22:23:21","slug":"recordamos-como-sera-el-receso-administrativo-municipal","status":"publish","type":"post","link":"https:\/\/www.oroverde.com.ar\/web\/recordamos-como-sera-el-receso-administrativo-municipal\/","title":{"rendered":"Recordamos c\u00f3mo ser\u00e1 el receso administrativo municipal"},"content":{"rendered":"\n<p>Comienza el 3 de enero el receso administrativo del Municipio de Oro Verde y se prolongar\u00e1 hasta el 23 del mismo mes. Se atender\u00e1 al p\u00fablico hasta el jueves 30 de diciembre y, transcurrido el receso, se retomar\u00e1 la atenci\u00f3n el martes 25 de enero.<br>Durante el receso se mantendr\u00e1n guardias y funcionar\u00e1n todos los servicios b\u00e1sicos, este a\u00f1o adem\u00e1s, podr\u00e1n seguir tramit\u00e1ndose las licencias de conducir de manera normal en el \u00e1rea de Tr\u00e1nsito e Inspecciones.<br>Algunos aspectos a tener en cuenta:<\/p>\n\n\n\n<p>Pago a proveedores:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Hasta el 23\/12 se recibir\u00e1n facturas para abonarse los d\u00edas siguientes. Posterior a esa fecha los pagos pasar\u00e1n para despu\u00e9s del receso.<br>Cobros en Tesorer\u00eda Municipal:<\/li><li>Se atender\u00e1 en Caja hasta 29\/12<br>Vencimientos:<br>\u2013 Obligaciones municipales como planes de pago, mejoras, terrenos sociales y la Tasa por Inspecci\u00f3n Sanitaria, Higiene y Profilaxis y Seguridad trasladan su vencimiento al 31 de enero, continuando luego el esquema habitual.<br>Licencia de conducir:<br>\u2013 Este a\u00f1o podr\u00e1n seguir tramit\u00e1ndose las licencias de conducir de manera normal en el \u00e1rea de Tr\u00e1nsito e Inspecciones. De 7 a 13 hs.<br>Ya que el Municipio no va a tener el \u00e1rea de tesorer\u00eda abierta, el pago del sellado municipal y la boleta del CENAT, ser\u00e1 \u00fanicamente a trav\u00e9s de Entre R\u00edos Servicios, siendo el lugar establecido para abonarlo en Avenida Intendente del Castillo N\u00ba 325.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Comienza el 3 de enero el receso administrativo del Municipio de Oro Verde y se prolongar\u00e1 hasta el 23 del mismo mes. Se atender\u00e1 al p\u00fablico hasta el jueves 30&#8230;<\/p>\n","protected":false},"author":6,"featured_media":623081,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[6,193],"tags":[],"class_list":["post-624526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-de-eventos","category-destacadas","wpcat-6-id","wpcat-193-id"],"_links":{"self":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/comments?post=624526"}],"version-history":[{"count":1,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624526\/revisions"}],"predecessor-version":[{"id":624527,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624526\/revisions\/624527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media\/623081"}],"wp:attachment":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media?parent=624526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/categories?post=624526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/tags?post=624526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}