{"id":624739,"date":"2022-03-15T20:15:06","date_gmt":"2022-03-15T23:15:06","guid":{"rendered":"https:\/\/www.oroverde.com.ar\/web\/?p=624739"},"modified":"2022-03-15T20:15:08","modified_gmt":"2022-03-15T23:15:08","slug":"cine-debate-una-mirada-critica-sobre-el-rol-de-las-mujeres-en-la-sociedad-reprogramado","status":"publish","type":"post","link":"https:\/\/www.oroverde.com.ar\/web\/cine-debate-una-mirada-critica-sobre-el-rol-de-las-mujeres-en-la-sociedad-reprogramado\/","title":{"rendered":"Cine debate \u201cUna mirada cr\u00edtica sobre el rol de las mujeres en la sociedad\u201d reprogramado"},"content":{"rendered":"\n<p>Esta propuesta que se enmarca dentro las actividades que lleva adelante el municipio por el mes de la mujer se reprograma para el martes 22 de marzo a las 20 horas. Ser\u00e1 en el Museo Conrado Hasenauer, ubicado en Los Tordos N\u00ba 241.<br>All\u00ed, se proyectar\u00e1n extractos de dibujitos animados y pel\u00edculas de Disney para problematizar las representaciones sociales de la feminidad y la mujer en la historia.<br>Estar\u00e1 a cargo de la responsable del \u00e1rea de Desarrollo Social municipal Sandra Hasenauer y la trabajadora social Paola C\u00f3rdoba.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta propuesta que se enmarca dentro las actividades que lleva adelante el municipio por el mes de la mujer se reprograma para el martes 22 de marzo a las 20&#8230;<\/p>\n","protected":false},"author":6,"featured_media":624713,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[6,21,36,1],"tags":[],"class_list":["post-624739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-de-eventos","category-breves","category-eventos","category-noticias","wpcat-6-id","wpcat-21-id","wpcat-36-id","wpcat-1-id"],"_links":{"self":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/comments?post=624739"}],"version-history":[{"count":1,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624739\/revisions"}],"predecessor-version":[{"id":624740,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624739\/revisions\/624740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media\/624713"}],"wp:attachment":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media?parent=624739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/categories?post=624739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/tags?post=624739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}