{"id":624938,"date":"2022-05-23T21:30:53","date_gmt":"2022-05-24T00:30:53","guid":{"rendered":"https:\/\/www.oroverde.com.ar\/web\/?p=624938"},"modified":"2022-05-23T21:30:57","modified_gmt":"2022-05-24T00:30:57","slug":"se-realizo-la-feria-de-intercambio-de-semillas-y-plantas-junto-a-una-charla-sobre-compostaje","status":"publish","type":"post","link":"https:\/\/www.oroverde.com.ar\/web\/se-realizo-la-feria-de-intercambio-de-semillas-y-plantas-junto-a-una-charla-sobre-compostaje\/","title":{"rendered":"Se realiz\u00f3 la feria de intercambio de semillas y plantas junto a una charla sobre compostaje"},"content":{"rendered":"\n<p>Se llev\u00f3 adelante el pasado s\u00e1bado por la tarde en el Centro Integrador Comunitario una Feria de Intercambio de Semillas y Plantas junto a una charla sobre compostaje a cargo del Ingeniero Agr\u00f3nomo Juli\u00e1n Parodi, integrante de la Fundaci\u00f3n CAUCE: Cultura Ambiental &#8211; Causa Ecologista. <\/p>\n\n\n\n<p>All\u00ed, los asistentes intercambiaron ideas y se brindaron pautas sobre este proceso. <\/p>\n\n\n\n<p>Tambi\u00e9n form\u00f3 parte de esta charla el Coordinador de Huertas urbanas y periurbanas agroecol\u00f3gicas de la localidad, Guzm\u00e1n Banquero, junto a huerteros y huerteras del parque hort\u00edcola e integrantes del taller de huerta org\u00e1nica municipal.<\/p>\n\n\n\n<p>Durante la jornada los asistentes intercambiaron semillas, bulbos y plantas sin que medie dinero.<\/p>\n\n\n\n<p>Adem\u00e1s se realiz\u00f3 el sorteo de composteras obtenidas por medio de una gesti\u00f3n en el Ministerio de Ambiente y Desarrollo Sostenible de la Naci\u00f3n.<\/p>\n\n\n\n<p>Participaron de esta jornada la viceintendenta Marianela Komar y la concejal Claudia Genolet.<\/p>\n\n\n\n<p>La Feria estuvo organizada por el Programa de Huertas Agroecol\u00f3gicas Urbanas y Periurbanas del Municipio de Oro Verde, la Red Huerteros y Huerteras local y la Fundaci\u00f3n CAUCE: Cultura Ambiental &#8211; Causa Ecologista, Tierra Viva Agroecolog\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se llev\u00f3 adelante el pasado s\u00e1bado por la tarde en el Centro Integrador Comunitario una Feria de Intercambio de Semillas y Plantas junto a una charla sobre compostaje a cargo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":624939,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-624938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","wpcat-10-id"],"_links":{"self":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/comments?post=624938"}],"version-history":[{"count":1,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624938\/revisions"}],"predecessor-version":[{"id":624940,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624938\/revisions\/624940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media\/624939"}],"wp:attachment":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media?parent=624938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/categories?post=624938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/tags?post=624938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}