{"id":624961,"date":"2022-06-03T13:18:00","date_gmt":"2022-06-03T16:18:00","guid":{"rendered":"https:\/\/www.oroverde.com.ar\/web\/?p=624961"},"modified":"2022-06-06T13:24:01","modified_gmt":"2022-06-06T16:24:01","slug":"preinscripcion-al-programa-educando-en-movimiento-3","status":"publish","type":"post","link":"https:\/\/www.oroverde.com.ar\/web\/preinscripcion-al-programa-educando-en-movimiento-3\/","title":{"rendered":"Preinscripci\u00f3n al programa educando en movimiento"},"content":{"rendered":"\n<p>El Municipio de Oro Verde abri\u00f3 la preinscripci\u00f3n al Programa \u201cEducando en Movimiento\u201d, del Instituto Becario Provincial, destinado a ni\u00f1as, ni\u00f1os y adolescentes entre los 6 y 13 a\u00f1os.<br>Las actividades se llevar\u00e1n a cabo, por la ma\u00f1ana, en el Centro Integrador Comunitario ubicado en Av. Los Cha\u00f1ares 397, lunes y mi\u00e9rcoles de 9 a 11 y por la tarde en el Club Atl\u00e9tico Oro Verde, ubicado en Los Jacarandaes 54 los lunes de 15 a 17 y jueves de 15.30 a 17.30.<br>Este programa tiene el objetivo de brindar un espacio de acompa\u00f1amiento para los ni\u00f1os y ni\u00f1as, y adolescentes entre los 6 y 13 a\u00f1os, en lugares que se asignar\u00e1n posteriormente, de acuerdo a la cantidad de inscriptos. All\u00ed, recibir\u00e1n apoyo en las materias escolares, y realizar\u00e1n actividades deportivas, culturales y recreativas. En estas clases, estar\u00e1n acompa\u00f1ados por profesores, con quienes realizar\u00e1n la tarea, tendr\u00e1n una merienda y tambi\u00e9n har\u00e1n actividades l\u00fadicas o deportivas.<br>Quienes deseen preinscribirse pueden hacerlo hasta el domingo 5 de junio inclusive, a trav\u00e9s del siguiente link: http:\/\/bitly.ws\/rVvX<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Municipio de Oro Verde abri\u00f3 la preinscripci\u00f3n al Programa \u201cEducando en Movimiento\u201d, del Instituto Becario Provincial, destinado a ni\u00f1as, ni\u00f1os y adolescentes entre los 6 y 13 a\u00f1os.Las actividades&#8230;<\/p>\n","protected":false},"author":6,"featured_media":624962,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[6,4,12,1,5,30],"tags":[],"class_list":["post-624961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-de-eventos","category-historias-de-vida","category-instituciones","category-noticias","category-noticias-municipales","category-salud","wpcat-6-id","wpcat-4-id","wpcat-12-id","wpcat-1-id","wpcat-5-id","wpcat-30-id"],"_links":{"self":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/comments?post=624961"}],"version-history":[{"count":1,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624961\/revisions"}],"predecessor-version":[{"id":624963,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/624961\/revisions\/624963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media\/624962"}],"wp:attachment":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media?parent=624961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/categories?post=624961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/tags?post=624961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}