{"id":625234,"date":"2022-08-20T10:11:26","date_gmt":"2022-08-20T13:11:26","guid":{"rendered":"https:\/\/www.oroverde.com.ar\/web\/?p=625234"},"modified":"2022-08-20T10:11:28","modified_gmt":"2022-08-20T13:11:28","slug":"servicios-de-la-sala-municipal-de-primeros-auxilios","status":"publish","type":"post","link":"https:\/\/www.oroverde.com.ar\/web\/servicios-de-la-sala-municipal-de-primeros-auxilios\/","title":{"rendered":"Servicios de la sala municipal de primeros auxilios"},"content":{"rendered":"\n<p>El Municipio difunde los nuevos cuales son los servicios con los que cuenta la Sala Municipal de Primeros Auxilios, Cris\u00f3logo Larralde, ubicada en Las Rosas, casi Camino de la Cuchilla de barrio El Triangular e informa que se modificaron algunos horarios de atenci\u00f3n que se detallan a continuaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Nutrici\u00f3n: Lic. Candela Rueda, lunes de 12 a 15 hs. y viernes de 10 a 13 hs.<\/li><li>Pediatr\u00eda: Dra. Soledad Vignuda, lunes y jueves de 9.30 a 11.30 hs. Martes de 8.30 a 10.30 hs.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Odontolog\u00eda: Dr. Gustavo Gabrovich. Martes, mi\u00e9rcoles y viernes de 9 a 10 hs.<\/li><li>M\u00e9dico cl\u00ednico: Dr. Quinteros, de lunes a mi\u00e9rcoles de 15.30 a 17.30 hs.<\/li><li>Dr. Bertozzi, jueves y viernes desde las 15 hs.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Obstetra: Carina Romero viernes de 9 a 11 hs.<\/li><li>Vacunaci\u00f3n: Lunes a viernes de 9 a 12 hs.<\/li><li>Enfermer\u00eda: de lunes a viernes de 8 a 18 hs. (Por la ma\u00f1ana Lucrecia Famea y Marcelo Quijada por la tarde)<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El Municipio difunde los nuevos cuales son los servicios con los que cuenta la Sala Municipal de Primeros Auxilios, Cris\u00f3logo Larralde, ubicada en Las Rosas, casi Camino de la Cuchilla&#8230;<\/p>\n","protected":false},"author":6,"featured_media":625235,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[6,21,193,12,1,5],"tags":[],"class_list":["post-625234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-de-eventos","category-breves","category-destacadas","category-instituciones","category-noticias","category-noticias-municipales","wpcat-6-id","wpcat-21-id","wpcat-193-id","wpcat-12-id","wpcat-1-id","wpcat-5-id"],"_links":{"self":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/625234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/comments?post=625234"}],"version-history":[{"count":1,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/625234\/revisions"}],"predecessor-version":[{"id":625236,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/625234\/revisions\/625236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media\/625235"}],"wp:attachment":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media?parent=625234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/categories?post=625234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/tags?post=625234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}