{"id":625585,"date":"2022-10-14T12:31:00","date_gmt":"2022-10-14T15:31:00","guid":{"rendered":"https:\/\/www.oroverde.com.ar\/web\/?p=625585"},"modified":"2022-10-15T12:32:39","modified_gmt":"2022-10-15T15:32:39","slug":"realizaran-una-capacitacion-abierta-a-la-comunidad-sobre-frutales","status":"publish","type":"post","link":"https:\/\/www.oroverde.com.ar\/web\/realizaran-una-capacitacion-abierta-a-la-comunidad-sobre-frutales\/","title":{"rendered":"Realizar\u00e1n una capacitaci\u00f3n abierta a la comunidad sobre frutales"},"content":{"rendered":"\n<p>Llevar\u00e1n adelante una capacitaci\u00f3n sobre el manejo y cuidado de plantas frutales. La misma forma parte de un ciclo de encuentros de encuentros en el departamento Paran\u00e1 para potenciar el cultivo de frutales. Es abierta a la comunidad, y tendr\u00e1 lugar el lunes 17 de octubre a las 16 hs. en el Sal\u00f3n Auditorio Municipal, sito en Los Canarios 391. No es necesario inscribirse previamente.<\/p>\n\n\n\n<p>Los temas que se abordar\u00e1n ser\u00e1n: principales plagas y su manejo en frutales \/ Enfermedades y su manejo \/ M\u00e9todos de multiplicaci\u00f3n de especies frutales. La actividad se enmarca dentro del Proyecto \u201cEspacio de intercambio de saberes para potenciar el cultivo de frutales en las colonias del Departamento Paran\u00e1\u201d, que se ejecuta desde la C\u00e1tedra de Fruticultura de la Facultad de Ciencias Agropecuarias, con el objetivo de compartir habilidades y conocimientos de pr\u00e1cticas frut\u00edcolas con los agricultores, que les permitan sostener producciones continuas y de calidad, favorecer el arraigo rural y rescatar saberes relacionados con este tipo de producciones.<\/p>\n\n\n\n<p>Cuenta tambi\u00e9n con la participaci\u00f3n de T\u00e9cnicos de la Secretar\u00eda de Agricultura Familiar, Campesina e Ind\u00edgena, del Ministerio de Agricultura de la Naci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llevar\u00e1n adelante una capacitaci\u00f3n sobre el manejo y cuidado de plantas frutales. La misma forma parte de un ciclo de encuentros de encuentros en el departamento Paran\u00e1 para potenciar el&#8230;<\/p>\n","protected":false},"author":6,"featured_media":625586,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[6,32,193,12,191,1,5,33,35],"tags":[],"class_list":["post-625585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-de-eventos","category-ambiente-saludable","category-destacadas","category-instituciones","category-naturaleza","category-noticias","category-noticias-municipales","category-obras","category-talleres","wpcat-6-id","wpcat-32-id","wpcat-193-id","wpcat-12-id","wpcat-191-id","wpcat-1-id","wpcat-5-id","wpcat-33-id","wpcat-35-id"],"_links":{"self":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/625585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/comments?post=625585"}],"version-history":[{"count":1,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/625585\/revisions"}],"predecessor-version":[{"id":625587,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/625585\/revisions\/625587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media\/625586"}],"wp:attachment":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media?parent=625585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/categories?post=625585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/tags?post=625585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}