{"id":625673,"date":"2022-10-31T19:25:00","date_gmt":"2022-10-31T22:25:00","guid":{"rendered":"https:\/\/www.oroverde.com.ar\/web\/?p=625673"},"modified":"2022-11-04T19:37:02","modified_gmt":"2022-11-04T22:37:02","slug":"recordamos-que-hasta-el-4-de-noviembre-se-puede-abonar-la-tasa-por-obras-sanitarias","status":"publish","type":"post","link":"https:\/\/www.oroverde.com.ar\/web\/recordamos-que-hasta-el-4-de-noviembre-se-puede-abonar-la-tasa-por-obras-sanitarias\/","title":{"rendered":"Recordamos que hasta el 4 de noviembre se puede abonar la tasa por obras sanitarias"},"content":{"rendered":"\n<p>Ante inconvenientes en el sistema inform\u00e1tico municipal, se generaron demoras en la emisi\u00f3n de los avisos de vencimiento de la Tasa por Obras Sanitarias y la posterior distribuci\u00f3n de los mismos, por esta situaci\u00f3n se prorrog\u00f3 a trav\u00e9s del decreto N\u00ba 201, el vencimiento del plazo de pago de la Tasa de Obras Sanitarias per\u00edodo N\u00ba05\/2022 al 4 de noviembre de este a\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante inconvenientes en el sistema inform\u00e1tico municipal, se generaron demoras en la emisi\u00f3n de los avisos de vencimiento de la Tasa por Obras Sanitarias y la posterior distribuci\u00f3n de los&#8230;<\/p>\n","protected":false},"author":6,"featured_media":625667,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[6,193,12,1,5],"tags":[],"class_list":["post-625673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-de-eventos","category-destacadas","category-instituciones","category-noticias","category-noticias-municipales","wpcat-6-id","wpcat-193-id","wpcat-12-id","wpcat-1-id","wpcat-5-id"],"_links":{"self":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/625673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/comments?post=625673"}],"version-history":[{"count":1,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/625673\/revisions"}],"predecessor-version":[{"id":625674,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/posts\/625673\/revisions\/625674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media\/625667"}],"wp:attachment":[{"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/media?parent=625673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/categories?post=625673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oroverde.com.ar\/web\/wp-json\/wp\/v2\/tags?post=625673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}